{"id":2875,"date":"2025-09-27T09:31:49","date_gmt":"2025-09-27T09:31:49","guid":{"rendered":"https:\/\/hinges-htan.com\/?post_type=wpkj_product&#038;p=2875"},"modified":"2025-12-18T01:42:37","modified_gmt":"2025-12-18T01:42:37","slug":"bisagra-oculta-de-acero-inoxidable","status":"publish","type":"wpkj_product","link":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/","title":{"rendered":"Bisagra oculta de acero inoxidable adecuada para aplicaciones pesadas"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Las bisagras ocultas de acero inoxidable XG02-056 con capacidad de apertura de 120 grados garantizan una instalaci\u00f3n segura y duradera. Fabricadas en acero inoxidable o hierro, soportan cargas pesadas, resisten la corrosi\u00f3n y soportan entornos dif\u00edciles. Ideales para veh\u00edculos, armarios industriales, recintos exteriores y equipos alimentarios o farmac\u00e9uticos.<\/p>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-4f90d47\" class=\"gspb_heading gspb_heading-id-gsbp-4f90d47\">Dibujo acotado<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"527\" src=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-Dimension-Drawing-1024x527.webp\" alt=\"XG02-056 Bisagra oculta de acero inoxidable Dibujo acotado\" class=\"wp-image-2876\" srcset=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-Dimension-Drawing-1024x527.webp 1024w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-Dimension-Drawing-300x154.webp 300w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-Dimension-Drawing-768x395.webp 768w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-Dimension-Drawing-18x9.webp 18w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-Dimension-Drawing.webp 1107w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>C\u00f3digo<\/td><td>N\u00ba de art\u00edculo<\/td><td>L<\/td><td>L1<\/td><td>L2<\/td><td>H<\/td><td>W1<\/td><td>W2<\/td><td>Material<\/td><td>Tratamiento de superficies<\/td><\/tr><tr><td>XG02-056-1<\/td><td>XG02-056-1S<\/td><td>90<\/td><td>50<\/td><td>25<\/td><td>23.5<\/td><td>27.5<\/td><td>16.5<\/td><td>SUS304<\/td><td>Acabado por vibraci\u00f3n<\/td><\/tr><tr><td>XG02-056-1<\/td><td>XG02-056-1<\/td><td>90<\/td><td>50<\/td><td>25<\/td><td>23.5<\/td><td>27.5<\/td><td>16.5<\/td><td>SPCC<\/td><td>Galvanizado<\/td><\/tr><tr><td>XG02-056-1A<\/td><td>XG02-056-1A<\/td><td>90<\/td><td>50<\/td><td>25<\/td><td>23.5<\/td><td>27.5<\/td><td>16.5<\/td><td rowspan=\"2\">SUS304<\/td><td rowspan=\"2\">Acabado por vibraci\u00f3n<\/td><\/tr><tr><td>XG02-056-2<\/td><td>XG02-056-2<\/td><td>90<\/td><td>51.5<\/td><td>25<\/td><td>23.5<\/td><td>33.5<\/td><td>21<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1001\" height=\"549\" src=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-Dimension-Drawing-1.webp\" alt=\"XG02-056 Bisagra oculta de acero inoxidable Dibujo acotado\" class=\"wp-image-2877\" srcset=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-Dimension-Drawing-1.webp 1001w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-Dimension-Drawing-1-300x165.webp 300w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-Dimension-Drawing-1-768x421.webp 768w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-Dimension-Drawing-1-18x10.webp 18w\" sizes=\"auto, (max-width: 1001px) 100vw, 1001px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>C\u00f3digo<\/td><td>N\u00ba de art\u00edculo<\/td><td>Material<\/td><td>Tratamiento de superficies<\/td><\/tr><tr><td>XG02-056-3<\/td><td>XG02-056-3<\/td><td>SUS304<\/td><td>Acabado por vibraci\u00f3n<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-6929a06\" class=\"gspb_heading gspb_heading-id-gsbp-6929a06\">PREGUNTAS FRECUENTES<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: \u00bfPara qu\u00e9 se utilizan las bisagras ocultas de acero inoxidable?<\/strong><br><strong>A:<\/strong> Las bisagras ocultas de acero inoxidable con apertura de 120\u00b0 son ideales para uso intensivo. Encajan perfectamente en veh\u00edculos, armarios industriales, recintos exteriores y equipos alimentarios o farmac\u00e9uticos. Con una instalaci\u00f3n soldada segura, ofrecen una durabilidad duradera y un aspecto limpio y sin tornillos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: \u00bfPuedo solicitar a su f\u00e1brica bisagras soldadas personalizadas?<\/strong><br><strong>A:<\/strong> Por supuesto. Ofrecemos servicios de personalizaci\u00f3n de bisagras para satisfacer sus necesidades. Puede elegir el tama\u00f1o, el material (acero inoxidable o hierro) y el acabado de la superficie. Nuestro equipo de f\u00e1brica trabaja en estrecha colaboraci\u00f3n con usted para dise\u00f1ar bisagras soldadas que se ajusten exactamente a los requisitos de su proyecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: \u00bfD\u00f3nde fabrican sus bisagras ocultas soldables?<\/strong><br><strong>A:<\/strong> Fabricamos todas las bisagras soldables ocultas directamente en nuestra propia f\u00e1brica. Este proceso pr\u00e1ctico de producci\u00f3n garantiza una calidad constante, una resistencia fiable y un estricto control de calidad para cada bisagra que suministramos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: \u00bfCon qu\u00e9 rapidez se pueden enviar las bisagras soldadas una vez realizado el pedido?<\/strong><br><strong>A:<\/strong> Enviamos r\u00e1pidamente bisagras de tama\u00f1o est\u00e1ndar desde nuestro almac\u00e9n, mientras que los pedidos personalizados siguen un calendario de producci\u00f3n acordado. Con opciones de entrega en todo el mundo, nos aseguramos de que sus bisagras lleguen a tiempo para que su proyecto avance sin problemas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: \u00bfCu\u00e1l es su pol\u00edtica de devoluci\u00f3n o sustituci\u00f3n de bisagras?<\/strong><br><strong>A:<\/strong> Respaldamos cada bisagra soldada con una s\u00f3lida garant\u00eda de calidad. Si recibe un art\u00edculo defectuoso o incorrecto, s\u00f3lo tiene que ponerse en contacto con nosotros para su devoluci\u00f3n, sustituci\u00f3n o reembolso. Nuestra pol\u00edtica de atenci\u00f3n al cliente hace que cada pedido est\u00e9 libre de preocupaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Las bisagras ocultas de acero inoxidable XG02-056 con capacidad de apertura de 120 grados garantizan una instalaci\u00f3n segura y duradera. Fabricadas en acero inoxidable o hierro, soportan cargas pesadas, resisten la corrosi\u00f3n y soportan entornos dif\u00edciles. Ideales para veh\u00edculos, armarios industriales, recintos exteriores y equipos alimentarios o farmac\u00e9uticos. C\u00f3digo Referencia L L1 L2 H W1 W2 Material Tratamiento de superficie [...]<\/p>","protected":false},"author":1,"featured_media":2878,"template":"","meta":{"_acf_changed":false,"_gspb_post_css":"","footnotes":""},"product_cat":[7],"product_tag":[],"class_list":["post-2875","wpkj_product","type-wpkj_product","status-publish","has-post-thumbnail","hentry","product_cat-concealed-hinges"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Concealed Stainless Steel Hinge suitable for heavy-duty applications - Hinges Manufacturer<\/title>\n<meta name=\"description\" content=\"Concealed Stainless Steel Hinge in stainless steel or iron. Heavy-duty, corrosion-resistant, perfect for vehicles, cabinets, and enclosures.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concealed Stainless Steel Hinge suitable for heavy-duty applications - Hinges Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Concealed Stainless Steel Hinge in stainless steel or iron. Heavy-duty, corrosion-resistant, perfect for vehicles, cabinets, and enclosures.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/\" \/>\n<meta property=\"og:site_name\" content=\"Hinges Manufacturer\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T01:42:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"507\" \/>\n\t<meta property=\"og:image:height\" content=\"504\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/\",\"url\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/\",\"name\":\"Concealed Stainless Steel Hinge suitable for heavy-duty applications - Hinges Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-2.webp\",\"datePublished\":\"2025-09-27T09:31:49+00:00\",\"dateModified\":\"2025-12-18T01:42:37+00:00\",\"description\":\"Concealed Stainless Steel Hinge in stainless steel or iron. Heavy-duty, corrosion-resistant, perfect for vehicles, cabinets, and enclosures.\",\"breadcrumb\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hinges-htan.com\/product\/concealed-stainless-steel-hinge\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/#primaryimage\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-2.webp\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-2.webp\",\"width\":507,\"height\":504,\"caption\":\"XG02-056 Concealed weldable hinges\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/hinges-htan.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u4ea7\u54c1\",\"item\":\"https:\/\/hinges-htan.com\/es\/productos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Concealed Stainless Steel Hinge suitable for heavy-duty applications\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hinges-htan.com\/es\/#website\",\"url\":\"https:\/\/hinges-htan.com\/es\/\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"description\":\"Cabinet &amp; Enclosure Hinge Solutions\",\"publisher\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hinges-htan.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hinges-htan.com\/es\/#organization\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"url\":\"https:\/\/hinges-htan.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hinges-htan.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"width\":726,\"height\":172,\"caption\":\"HTAN Industrial Hinges Manufacturer\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bisagra oculta de acero inoxidable adecuada para aplicaciones pesadas - Fabricante de bisagras","description":"Bisagra oculta de acero inoxidable en acero inoxidable o hierro. Resistente a la corrosi\u00f3n, perfecta para veh\u00edculos, armarios y recintos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/","og_locale":"es_ES","og_type":"article","og_title":"Concealed Stainless Steel Hinge suitable for heavy-duty applications - Hinges Manufacturer","og_description":"Concealed Stainless Steel Hinge in stainless steel or iron. Heavy-duty, corrosion-resistant, perfect for vehicles, cabinets, and enclosures.","og_url":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/","og_site_name":"Hinges Manufacturer","article_modified_time":"2025-12-18T01:42:37+00:00","og_image":[{"width":507,"height":504,"url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-2.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/","url":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/","name":"Bisagra oculta de acero inoxidable adecuada para aplicaciones pesadas - Fabricante de bisagras","isPartOf":{"@id":"https:\/\/hinges-htan.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/#primaryimage"},"image":{"@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/#primaryimage"},"thumbnailUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-2.webp","datePublished":"2025-09-27T09:31:49+00:00","dateModified":"2025-12-18T01:42:37+00:00","description":"Bisagra oculta de acero inoxidable en acero inoxidable o hierro. Resistente a la corrosi\u00f3n, perfecta para veh\u00edculos, armarios y recintos.","breadcrumb":{"@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hinges-htan.com\/product\/concealed-stainless-steel-hinge\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/#primaryimage","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-2.webp","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-056-Concealed-weldable-hinges-2.webp","width":507,"height":504,"caption":"XG02-056 Concealed weldable hinges"},{"@type":"BreadcrumbList","@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-oculta-de-acero-inoxidable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hinges-htan.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u4ea7\u54c1","item":"https:\/\/hinges-htan.com\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Concealed Stainless Steel Hinge suitable for heavy-duty applications"}]},{"@type":"WebSite","@id":"https:\/\/hinges-htan.com\/es\/#website","url":"https:\/\/hinges-htan.com\/es\/","name":"Fabricante de bisagras industriales HTAN","description":"Soluciones de bisagras para armarios y cajas","publisher":{"@id":"https:\/\/hinges-htan.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hinges-htan.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hinges-htan.com\/es\/#organization","name":"Fabricante de bisagras industriales HTAN","url":"https:\/\/hinges-htan.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hinges-htan.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","width":726,"height":172,"caption":"HTAN Industrial Hinges Manufacturer"},"image":{"@id":"https:\/\/hinges-htan.com\/es\/#\/schema\/logo\/image\/"}}]}},"acf":{"_product_image_gallery":[2879,2880,2881,2882,2883,2884,2885],"_product_excerpt":"Manufacturer: HTAN\r\nModel: XG02-056\r\nUnit Price: Get Latest Price\r\nMOQ: 1 Piece\r\nLead Time: In Stock (Ships within 24h) \/20-25 Days for Custom\r\nCustomization: OEM \/ ODM Support","post_download_file":2886},"_links":{"self":[{"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/wpkj_product\/2875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/wpkj_product"}],"about":[{"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/types\/wpkj_product"}],"author":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/wpkj_product\/2875\/revisions"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/2885"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/2884"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/2883"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/2882"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/2881"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/2880"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/2879"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/2878"}],"wp:attachment":[{"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media?parent=2875"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/product_cat?post=2875"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/product_tag?post=2875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}