{"id":3375,"date":"2025-10-13T07:41:07","date_gmt":"2025-10-13T07:41:07","guid":{"rendered":"https:\/\/hinges-htan.com\/?post_type=wpkj_product&#038;p=3375"},"modified":"2025-12-17T07:21:38","modified_gmt":"2025-12-17T07:21:38","slug":"bisagra-de-aleacion-de-zinc-de-alta-resistencia","status":"publish","type":"wpkj_product","link":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/","title":{"rendered":"Bisagra resistente de aleaci\u00f3n de zinc 90\u00d760 mm"},"content":{"rendered":"<p class=\"wp-block-paragraph\">XG02-030-2 Bisagra de aleaci\u00f3n de zinc resistente (90\u00d760 mm, 8 mm de grosor) dise\u00f1ada para armarios industriales y puertas de maquinaria. Con revestimiento de polvo negro para resistir la corrosi\u00f3n, orificios avellanados para una instalaci\u00f3n segura y gran capacidad de carga, ideal para equipos pesados, veh\u00edculos y armarios exteriores.<\/p>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-e85507f\" class=\"gspb_heading gspb_heading-id-gsbp-e85507f\">Dibujo acotado<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"811\" height=\"598\" src=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge.webp\" alt=\"XG02-030-2 Bisagra de aleaci\u00f3n de zinc resistente Dibujo acotado\" class=\"wp-image-3376\" srcset=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge.webp 811w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge-300x221.webp 300w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge-768x566.webp 768w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge-16x12.webp 16w\" sizes=\"auto, (max-width: 811px) 100vw, 811px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">C\u00f3digo<\/td><td class=\"has-text-align-center\" data-align=\"center\">N\u00ba de art\u00edculo<\/td><td class=\"has-text-align-center\" data-align=\"center\">Material<\/td><td class=\"has-text-align-center\" data-align=\"center\">Tratamiento de superficies<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">XG02-030-2<\/td><td class=\"has-text-align-center\" data-align=\"center\">XG02-030-2<\/td><td class=\"has-text-align-center\" data-align=\"center\">ZDC<\/td><td class=\"has-text-align-center\" data-align=\"center\">Negro<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-ee71ad8\" class=\"gspb_heading gspb_heading-id-gsbp-ee71ad8\">PREGUNTAS FRECUENTES<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: \u00bfQu\u00e9 hace que esta bisagra de aleaci\u00f3n de zinc de alta resistencia sea adecuada para uso industrial?<\/strong><br>R:Esta bisagra est\u00e1 fabricada en aleaci\u00f3n de zinc de alta resistencia con un dise\u00f1o de 8 mm de grosor, que ofrece una excelente capacidad de carga y estabilidad. Su acabado con recubrimiento en polvo negro proporciona resistencia a la corrosi\u00f3n, por lo que es ideal para armarios industriales, puertas de maquinaria y recintos exteriores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P:\u00bfPuedo personalizar el tama\u00f1o, el color o el tipo de montaje de esta bisagra?<\/strong><br>R:\u00a1S\u00ed! Ofrecemos servicios de OEM y personalizaci\u00f3n. Puede solicitar dimensiones espec\u00edficas, acabados superficiales u opciones de montaje con tornillos\/soldadura para que se adapten perfectamente a su aplicaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: \u00bfSu f\u00e1brica puede producir grandes vol\u00famenes?<\/strong><br>R:Por supuesto. Como proveedor directo de f\u00e1brica, nos especializamos en la producci\u00f3n de bisagras de alta resistencia a granel con un estricto control de calidad y precios competitivos. Tambi\u00e9n ofrecemos embalajes personalizados y grabado de logotipos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P:\u00bfCon qu\u00e9 rapidez se entregan las bisagras tras el pedido?<\/strong><br>R:Mantenemos existencias suficientes para los modelos est\u00e1ndar. <strong>Bisagras de alta resistencia en stock. Env\u00edo en 24 horas.<\/strong> Para pedidos al por mayor o personalizados, la producci\u00f3n suele tardar entre 20 y 25 d\u00edas, y ofrecemos un env\u00edo r\u00e1pido a todo el mundo a trav\u00e9s de socios log\u00edsticos de confianza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: \u00bfCu\u00e1l es su pol\u00edtica de devoluciones y cambios?<\/strong><br>R:Estamos a favor de la calidad de nuestros productos. Si usted recibe art\u00edculos defectuosos o da\u00f1ados, p\u00f3ngase en contacto con nosotros dentro de 7 d\u00edas para un reemplazo r\u00e1pido o reembolso completo. La satisfacci\u00f3n del cliente es nuestra m\u00e1xima prioridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>XG02-030-2 Bisagra de aleaci\u00f3n de zinc de alta resistencia (90 \u00d7 60 mm, 8 mm de grosor) dise\u00f1ada para armarios industriales y puertas de maquinaria. Cuenta con un recubrimiento en polvo negro que la hace resistente a la corrosi\u00f3n, orificios avellanados para una instalaci\u00f3n segura y una gran capacidad de carga, lo que la hace ideal para maquinaria pesada, veh\u00edculos y recintos al aire libre. C\u00f3digo N.\u00ba de art\u00edculo Material Tratamiento superficial XG02-030-2 XG02-030-2 ZDC Negro P: \u00bfQu\u00e9 hace que esta bisagra de aleaci\u00f3n de zinc de alta resistencia [\u2026]<\/p>","protected":false},"author":1,"featured_media":3377,"template":"","meta":{"_acf_changed":false,"_gspb_post_css":"","footnotes":""},"product_cat":[6],"product_tag":[],"class_list":["post-3375","wpkj_product","type-wpkj_product","status-publish","has-post-thumbnail","hentry","product_cat-heavy-duty-hinges"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Heavy-Duty Zinc Alloy Hinge 90\u00d760mm - Hinges Manufacturer<\/title>\n<meta name=\"description\" content=\"Durable 90\u00d760mm zinc alloy hinge with black coating, corrosion resistance, and strong load capacity\u2014ideal for industrial cabinets.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Heavy-Duty Zinc Alloy Hinge 90\u00d760mm - Hinges Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Durable 90\u00d760mm zinc alloy hinge with black coating, corrosion resistance, and strong load capacity\u2014ideal for industrial cabinets.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Hinges Manufacturer\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T07:21:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/\",\"url\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/\",\"name\":\"Heavy-Duty Zinc Alloy Hinge 90\u00d760mm - Hinges Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge-1.webp\",\"datePublished\":\"2025-10-13T07:41:07+00:00\",\"dateModified\":\"2025-12-17T07:21:38+00:00\",\"description\":\"Durable 90\u00d760mm zinc alloy hinge with black coating, corrosion resistance, and strong load capacity\u2014ideal for industrial cabinets.\",\"breadcrumb\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hinges-htan.com\/product\/heavy-duty-zinc-alloy-hinge\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/#primaryimage\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge-1.webp\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge-1.webp\",\"width\":500,\"height\":501,\"caption\":\"XG02-030-2 Heavy-duty zinc alloy hinge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/hinges-htan.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u4ea7\u54c1\",\"item\":\"https:\/\/hinges-htan.com\/es\/productos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Heavy-Duty Zinc Alloy Hinge 90\u00d760mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hinges-htan.com\/es\/#website\",\"url\":\"https:\/\/hinges-htan.com\/es\/\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"description\":\"Cabinet &amp; Enclosure Hinge Solutions\",\"publisher\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hinges-htan.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hinges-htan.com\/es\/#organization\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"url\":\"https:\/\/hinges-htan.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hinges-htan.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"width\":726,\"height\":172,\"caption\":\"HTAN Industrial Hinges Manufacturer\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bisagra resistente de aleaci\u00f3n de zinc 90\u00d760mm - Fabricante de bisagras","description":"Duradera bisagra de aleaci\u00f3n de zinc de 90\u00d760 mm con revestimiento negro, resistencia a la corrosi\u00f3n y gran capacidad de carga, ideal para armarios industriales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/","og_locale":"es_ES","og_type":"article","og_title":"Heavy-Duty Zinc Alloy Hinge 90\u00d760mm - Hinges Manufacturer","og_description":"Durable 90\u00d760mm zinc alloy hinge with black coating, corrosion resistance, and strong load capacity\u2014ideal for industrial cabinets.","og_url":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/","og_site_name":"Hinges Manufacturer","article_modified_time":"2025-12-17T07:21:38+00:00","og_image":[{"width":500,"height":501,"url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge-1.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/","url":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/","name":"Bisagra resistente de aleaci\u00f3n de zinc 90\u00d760mm - Fabricante de bisagras","isPartOf":{"@id":"https:\/\/hinges-htan.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/#primaryimage"},"image":{"@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/#primaryimage"},"thumbnailUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge-1.webp","datePublished":"2025-10-13T07:41:07+00:00","dateModified":"2025-12-17T07:21:38+00:00","description":"Duradera bisagra de aleaci\u00f3n de zinc de 90\u00d760 mm con revestimiento negro, resistencia a la corrosi\u00f3n y gran capacidad de carga, ideal para armarios industriales.","breadcrumb":{"@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hinges-htan.com\/product\/heavy-duty-zinc-alloy-hinge\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/#primaryimage","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge-1.webp","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-030-2-Heavy-duty-zinc-alloy-hinge-1.webp","width":500,"height":501,"caption":"XG02-030-2 Heavy-duty zinc alloy hinge"},{"@type":"BreadcrumbList","@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-aleacion-de-zinc-de-alta-resistencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hinges-htan.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u4ea7\u54c1","item":"https:\/\/hinges-htan.com\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Heavy-Duty Zinc Alloy Hinge 90\u00d760mm"}]},{"@type":"WebSite","@id":"https:\/\/hinges-htan.com\/es\/#website","url":"https:\/\/hinges-htan.com\/es\/","name":"Fabricante de bisagras industriales HTAN","description":"Soluciones de bisagras para armarios y cajas","publisher":{"@id":"https:\/\/hinges-htan.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hinges-htan.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hinges-htan.com\/es\/#organization","name":"Fabricante de bisagras industriales HTAN","url":"https:\/\/hinges-htan.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hinges-htan.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","width":726,"height":172,"caption":"HTAN Industrial Hinges Manufacturer"},"image":{"@id":"https:\/\/hinges-htan.com\/es\/#\/schema\/logo\/image\/"}}]}},"acf":{"_product_image_gallery":[3378],"_product_excerpt":"Manufacturer: HTAN\r\nModel: XG02-030-2\r\nUnit Price: Get Latest Price\r\nMOQ: 1 Piece\r\nLead Time: In Stock (Ships within 24h) \/20-25 Days for Custom\r\nCustomization: OEM \/ ODM Support","post_download_file":3379},"_links":{"self":[{"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/wpkj_product\/3375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/wpkj_product"}],"about":[{"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/types\/wpkj_product"}],"author":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/wpkj_product\/3375\/revisions"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/3378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/3377"}],"wp:attachment":[{"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media?parent=3375"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/product_cat?post=3375"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/product_tag?post=3375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}