{"id":3722,"date":"2025-10-21T02:29:59","date_gmt":"2025-10-21T02:29:59","guid":{"rendered":"https:\/\/hinges-htan.com\/?post_type=wpkj_product&#038;p=3722"},"modified":"2025-12-17T06:08:03","modified_gmt":"2025-12-17T06:08:03","slug":"bisagra-de-torsion-ajustable-3","status":"publish","type":"wpkj_product","link":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/","title":{"rendered":"Bisagra de torsi\u00f3n ajustable | Acero inoxidable 304, sujeci\u00f3n en cualquier \u00e1ngulo"},"content":{"rendered":"<p class=\"wp-block-paragraph\">XG11-056 Bisagra de par ajustable (0,1-5,0 N-m) fabricada en acero inoxidable 304 para mayor resistencia a la corrosi\u00f3n e higiene. Ofrece rotaci\u00f3n de 360\u00b0, posicionamiento preciso y protecci\u00f3n contra sobrecargas; ideal para brazos rob\u00f3ticos, dispositivos m\u00e9dicos, instrumentos \u00f3pticos y electr\u00f3nica de gama alta.<\/p>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-7683fc7\" class=\"gspb_heading gspb_heading-id-gsbp-7683fc7\">Dibujo acotado<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"582\" src=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge-Dimension-Drawing-1024x582.webp\" alt=\"G11-056 Bisagra de torsi\u00f3n ajustable Dibujo acotado\" class=\"wp-image-3723\" srcset=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge-Dimension-Drawing-1024x582.webp 1024w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge-Dimension-Drawing-300x170.webp 300w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge-Dimension-Drawing-768x436.webp 768w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge-Dimension-Drawing-18x10.webp 18w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge-Dimension-Drawing.webp 1061w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">C\u00f3digo<\/td><td class=\"has-text-align-center\" data-align=\"center\">N\u00famero de art\u00edculo<\/td><td class=\"has-text-align-center\" data-align=\"center\">Par (N-m)<\/td><td class=\"has-text-align-center\" data-align=\"center\">Par (kgf-cm)<\/td><td class=\"has-text-align-center\" data-align=\"center\">Material<\/td><td class=\"has-text-align-center\" data-align=\"center\">Tratamiento de superficies<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">XG11-056<\/td><td class=\"has-text-align-center\" data-align=\"center\">XG11-056<\/td><td class=\"has-text-align-center\" data-align=\"center\">0.1-5<\/td><td class=\"has-text-align-center\" data-align=\"center\">1-50<\/td><td class=\"has-text-align-center\" data-align=\"center\">SUS303<\/td><td class=\"has-text-align-center\" data-align=\"center\">Color natural<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-bdbf97e\" class=\"gspb_heading gspb_heading-id-gsbp-bdbf97e\">PREGUNTAS FRECUENTES<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: \u00bfQu\u00e9 es una bisagra de torsi\u00f3n ajustable y por qu\u00e9 es importante?<\/strong><br>R:Una bisagra de par ajustable controla la suavidad con la que giran dos piezas conectadas. Este modelo ofrece un rango de par de <strong>0,1-5,0 N-m<\/strong> y utiliza <strong>Acero inoxidable 304<\/strong>que resiste de forma natural a la corrosi\u00f3n y mantiene limpias las superficies. Permite <strong>Rotaci\u00f3n completa de 360<\/strong> y <strong>sujeci\u00f3n en cualquier \u00e1ngulo<\/strong>, lo que da a los ingenieros plena libertad de dise\u00f1o. Adem\u00e1s, el <strong>protecci\u00f3n contra sobrecarga<\/strong> evita da\u00f1os cuando la fuerza supera el par establecido. Como resultado, funciona de forma fiable en <strong>brazos rob\u00f3ticos, dispositivos m\u00e9dicos, instrumentos \u00f3pticos<\/strong>y <strong>electr\u00f3nica de gama alta<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: \u00bfPuedo personalizar esta bisagra dinamom\u00e9trica para mi proyecto?<\/strong><br>R:Sin duda. Nuestro equipo de ingenieros trabaja estrechamente con usted para desarrollar <strong>soluciones personalizadas de bisagras dinamom\u00e9tricas<\/strong> que se ajusten exactamente a sus necesidades. Puede especificar el <strong>rango de par<\/strong>, <strong>dimensiones de las bisagras<\/strong>, <strong>estilo de montaje<\/strong>y <strong>acabado superficial<\/strong>-desde acero inoxidable cepillado hasta acero inoxidable pulido. Y lo que es m\u00e1s importante, apoyamos <strong>Servicios OEM y ODM<\/strong>para que pueda crear bisagras para <strong>automatizaci\u00f3n industrial<\/strong>, <strong>instrumental m\u00e9dico<\/strong>o <strong>electr\u00f3nica de consumo<\/strong> que coincidan con la identidad de su marca. Adem\u00e1s, ofrecemos grabado de logotipos y envases personalizados para mejorar su l\u00ednea de productos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: \u00bfFabrican estas bisagras de torsi\u00f3n en su propia f\u00e1brica?<\/strong><br>R: S\u00ed. Dirigimos nuestra propia <strong>F\u00e1brica de bisagras dinamom\u00e9tricas<\/strong>equipada con avanzadas m\u00e1quinas CNC y herramientas de ensayo de precisi\u00f3n. Este sistema de producci\u00f3n directa nos permite controlar totalmente la calidad y la uniformidad. En lugar de depender de intermediarios, usted obtiene <strong>precios directos de f\u00e1brica<\/strong>Adem\u00e1s, aceptamos auditor\u00edas de f\u00e1brica e inspecciones de terceros para garantizar la transparencia y la confianza en cada pedido. Adem\u00e1s, aceptamos auditor\u00edas de f\u00e1brica e inspecciones de terceros para garantizar la transparencia y la confianza en cada pedido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P:\u00bfEn cu\u00e1nto tiempo pueden enviar mi pedido?<\/strong><br>R:Las bisagras de torsi\u00f3n est\u00e1ndar est\u00e1n en stock y se env\u00edan en 24 horas, mientras que los pedidos personalizados tardan aproximadamente <strong>20-25 d\u00edas<\/strong> en funci\u00f3n de la complejidad y la cantidad. Para necesidades urgentes, tambi\u00e9n ofrecemos <strong>producci\u00f3n acelerada y env\u00edo urgente<\/strong> opciones. Una vez que su pedido sale de nuestro almac\u00e9n, le enviamos un n\u00famero de seguimiento para que pueda seguir el env\u00edo en tiempo real. De este modo, siempre estar\u00e1 informado desde el pedido hasta la entrega.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: \u00bfCu\u00e1l es su pol\u00edtica de devoluciones y cambios?<\/strong><br>R: Respaldamos la calidad de todas las bisagras que fabricamos. Si surge alg\u00fan problema, como especificaciones incorrectas o da\u00f1os en el producto, p\u00f3ngase en contacto con nosotros en un plazo de 24 horas. <strong>30 d\u00edas<\/strong> de recepci\u00f3n. Nuestro equipo de servicio organizar\u00e1 r\u00e1pidamente una <strong>devoluci\u00f3n, sustituci\u00f3n o asistencia completa<\/strong>. Adem\u00e1s, tambi\u00e9n ofrecemos asistencia t\u00e9cnica a largo plazo para la instalaci\u00f3n, el ajuste del par y el mantenimiento. Por este motivo, los clientes nos eligen no s\u00f3lo por nuestros productos, sino tambi\u00e9n por nuestro compromiso con un servicio fiable y una colaboraci\u00f3n continua.<\/p>","protected":false},"excerpt":{"rendered":"<p>XG11-056 Bisagra de par ajustable (0,1\u20135,0 N\u00b7m) fabricada en acero inoxidable 304 para garantizar la resistencia a la corrosi\u00f3n y la higiene. Ofrece una rotaci\u00f3n de 360\u00b0, un posicionamiento preciso y protecci\u00f3n contra sobrecargas, lo que la hace ideal para brazos rob\u00f3ticos, dispositivos m\u00e9dicos, instrumentos \u00f3pticos y electr\u00f3nica de alta gama. C\u00f3digo N\u00famero de art\u00edculo Par (N\u00b7m) Par (kgf\u00b7cm) Material Acabado superficial XG11-056 XG11-056 0,1\u20135 1\u201350 SUS303 Color natural P: \u00bfQu\u00e9 es un [\u2026]<\/p>","protected":false},"author":1,"featured_media":3724,"template":"","meta":{"_acf_changed":false,"_gspb_post_css":"#gspb_heading-id-gsbp-bdbf97e{margin-bottom:0}","footnotes":""},"product_cat":[4],"product_tag":[],"class_list":["post-3722","wpkj_product","type-wpkj_product","status-publish","has-post-thumbnail","hentry","product_cat-torque-hinges"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Adjustable Torque Hinge | 304 Stainless Steel, Any-Angle Hold - Hinges Manufacturer<\/title>\n<meta name=\"description\" content=\"Adjustable torque hinge (0.1\u20135.0 N\u00b7m) in 304 stainless steel offers 360\u00b0 rotation, and overload protection for industrial and medical use.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adjustable Torque Hinge | 304 Stainless Steel, Any-Angle Hold - Hinges Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Adjustable torque hinge (0.1\u20135.0 N\u00b7m) in 304 stainless steel offers 360\u00b0 rotation, and overload protection for industrial and medical use.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Hinges Manufacturer\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T06:08:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/\",\"url\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/\",\"name\":\"Adjustable Torque Hinge | 304 Stainless Steel, Any-Angle Hold - Hinges Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge.webp\",\"datePublished\":\"2025-10-21T02:29:59+00:00\",\"dateModified\":\"2025-12-17T06:08:03+00:00\",\"description\":\"Adjustable torque hinge (0.1\u20135.0 N\u00b7m) in 304 stainless steel offers 360\u00b0 rotation, and overload protection for industrial and medical use.\",\"breadcrumb\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hinges-htan.com\/product\/adjustable-torque-hinge-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/#primaryimage\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge.webp\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge.webp\",\"width\":500,\"height\":500,\"caption\":\"G11-056 Adjustable torque hinge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/hinges-htan.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u4ea7\u54c1\",\"item\":\"https:\/\/hinges-htan.com\/es\/productos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adjustable Torque Hinge | 304 Stainless Steel, Any-Angle Hold\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hinges-htan.com\/es\/#website\",\"url\":\"https:\/\/hinges-htan.com\/es\/\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"description\":\"Cabinet &amp; Enclosure Hinge Solutions\",\"publisher\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hinges-htan.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hinges-htan.com\/es\/#organization\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"url\":\"https:\/\/hinges-htan.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/hinges-htan.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"width\":726,\"height\":172,\"caption\":\"HTAN Industrial Hinges Manufacturer\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bisagra de torsi\u00f3n ajustable | Acero inoxidable 304, sujeci\u00f3n en cualquier \u00e1ngulo - Hinges Manufacturer","description":"La bisagra de par ajustable (0,1-5,0 N-m) de acero inoxidable 304 ofrece una rotaci\u00f3n de 360\u00b0 y protecci\u00f3n contra sobrecargas para uso industrial y m\u00e9dico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/","og_locale":"es_ES","og_type":"article","og_title":"Adjustable Torque Hinge | 304 Stainless Steel, Any-Angle Hold - Hinges Manufacturer","og_description":"Adjustable torque hinge (0.1\u20135.0 N\u00b7m) in 304 stainless steel offers 360\u00b0 rotation, and overload protection for industrial and medical use.","og_url":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/","og_site_name":"Hinges Manufacturer","article_modified_time":"2025-12-17T06:08:03+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/","url":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/","name":"Bisagra de torsi\u00f3n ajustable | Acero inoxidable 304, sujeci\u00f3n en cualquier \u00e1ngulo - Hinges Manufacturer","isPartOf":{"@id":"https:\/\/hinges-htan.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/#primaryimage"},"image":{"@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/#primaryimage"},"thumbnailUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge.webp","datePublished":"2025-10-21T02:29:59+00:00","dateModified":"2025-12-17T06:08:03+00:00","description":"La bisagra de par ajustable (0,1-5,0 N-m) de acero inoxidable 304 ofrece una rotaci\u00f3n de 360\u00b0 y protecci\u00f3n contra sobrecargas para uso industrial y m\u00e9dico.","breadcrumb":{"@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hinges-htan.com\/product\/adjustable-torque-hinge-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/#primaryimage","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge.webp","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/G11-056-Adjustable-torque-hinge.webp","width":500,"height":500,"caption":"G11-056 Adjustable torque hinge"},{"@type":"BreadcrumbList","@id":"https:\/\/hinges-htan.com\/es\/producto\/bisagra-de-torsion-ajustable-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/hinges-htan.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u4ea7\u54c1","item":"https:\/\/hinges-htan.com\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Adjustable Torque Hinge | 304 Stainless Steel, Any-Angle Hold"}]},{"@type":"WebSite","@id":"https:\/\/hinges-htan.com\/es\/#website","url":"https:\/\/hinges-htan.com\/es\/","name":"Fabricante de bisagras industriales HTAN","description":"Soluciones de bisagras para armarios y cajas","publisher":{"@id":"https:\/\/hinges-htan.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hinges-htan.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hinges-htan.com\/es\/#organization","name":"Fabricante de bisagras industriales HTAN","url":"https:\/\/hinges-htan.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hinges-htan.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","width":726,"height":172,"caption":"HTAN Industrial Hinges Manufacturer"},"image":{"@id":"https:\/\/hinges-htan.com\/es\/#\/schema\/logo\/image\/"}}]}},"acf":{"_product_image_gallery":[3725,3726,3727,3728],"_product_excerpt":"Manufacturer: HTAN\r\nModel: XG11-056\r\nUnit Price: Get Latest Price\r\nMOQ: 1 Piece\r\nLead Time: In Stock (Ships within 24h) \/20-25 Days for Custom\r\nCustomization: OEM \/ ODM Support","post_download_file":3729},"_links":{"self":[{"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/wpkj_product\/3722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/wpkj_product"}],"about":[{"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/types\/wpkj_product"}],"author":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/wpkj_product\/3722\/revisions"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/3728"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/3727"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/3726"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/3725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media\/3724"}],"wp:attachment":[{"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/media?parent=3722"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/product_cat?post=3722"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hinges-htan.com\/es\/wp-json\/wp\/v2\/product_tag?post=3722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}