{"id":3439,"date":"2025-10-14T08:06:14","date_gmt":"2025-10-14T08:06:14","guid":{"rendered":"https:\/\/hinges-htan.com\/?post_type=wpkj_product&#038;p=3439"},"modified":"2025-12-17T07:07:14","modified_gmt":"2025-12-17T07:07:14","slug":"cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere","status":"publish","type":"wpkj_product","link":"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/","title":{"rendered":"Cerniera per congelatori in acciaio inox per uso intensivo per porte di celle frigorifere"},"content":{"rendered":"<p class=\"wp-block-paragraph\">XG02-017 Cerniera per congelatori in acciaio inox per impieghi gravosi per porte di celle frigorifere progettata per una durata estrema in ambienti a bassa temperatura e alta umidit\u00e0. La sua struttura rinforzata garantisce una capacit\u00e0 di carico superiore, resistenza alla corrosione e affidabilit\u00e0 a lungo termine, perfetta per i congelatori walk-in, gli impianti di lavorazione degli alimenti e le celle frigorifere farmaceutiche.<\/p>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-db0483d\" class=\"gspb_heading gspb_heading-id-gsbp-db0483d\">Disegno quotato<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"534\" src=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-Dimension-Drawing.webp\" alt=\"XG02-017 Cerniera per congelatori in acciaio inox per porte di celle frigorifere Disegno dimensionale\" class=\"wp-image-3442\" srcset=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-Dimension-Drawing.webp 945w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-Dimension-Drawing-300x170.webp 300w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-Dimension-Drawing-768x434.webp 768w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-Dimension-Drawing-18x10.webp 18w\" sizes=\"auto, (max-width: 945px) 100vw, 945px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Codice<\/td><td class=\"has-text-align-center\" data-align=\"center\">Articolo n.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Materiale<\/td><td class=\"has-text-align-center\" data-align=\"center\">Trattamento della superficie<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">XG02-017<\/td><td class=\"has-text-align-center\" data-align=\"center\">XG02-017<\/td><td class=\"has-text-align-center\" data-align=\"center\">SUS304<\/td><td class=\"has-text-align-center\" data-align=\"center\">Specchio<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-5241f1e\" class=\"gspb_heading gspb_heading-id-gsbp-5241f1e\">FAQ<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"q-why-choose-this-stainless-steel-heavy-duty-freezer-hinge-for-cold-storage-doors\"><strong>D: Perch\u00e9 scegliere questa cerniera per congelatore in acciaio inox per impieghi gravosi per le porte delle celle frigorifere?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R: Questa cerniera utilizza acciaio inossidabile di prima qualit\u00e0 per una forte capacit\u00e0 di carico e resistenza alla corrosione. Funziona in modo affidabile in ambienti a bassa temperatura e alta umidit\u00e0, come le cabine frigorifere, gli impianti alimentari e le celle frigorifere farmaceutiche.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"q-do-you-offer-custom-freezer-hinge-designs-for-special-applications\"><strong>D: Offrite design di cerniere per congelatori personalizzati per applicazioni speciali?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R:S\u00ec, la nostra fabbrica progetta e costruisce <strong>cerniere per congelatori personalizzate<\/strong> per adattarsi alle vostre esigenze. Il nostro team di ricerca e sviluppo regola le dimensioni, la coppia e il materiale per adattarsi perfettamente alle specifiche della vostra porta.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"q-how-do-you-control-quality-during-production\"><strong>D: Come controllate la qualit\u00e0 durante la produzione?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R:Noi gestiamo <strong>produzione e collaudo interamente in-house<\/strong>. I nostri ingegneri controllano ogni cerniera per verificare la resistenza alla corrosione, la forza di carico e le prestazioni in termini di temperatura, per garantire un funzionamento affidabile in ambienti difficili.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"q-how-fast-can-you-deliver-orders\"><strong>D: In quanto tempo consegnate gli ordini?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A:<strong>Cerniere per impieghi gravosi in stock. Spedizione entro 24 ore<\/strong>. Per gli ordini di grandi dimensioni, utilizziamo il trasporto espresso, aereo o marittimo per garantire una consegna rapida e sicura in tutto il mondo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"q-what-s-your-return-policy-if-there-s-a-problem\"><strong>D: Qual \u00e8 la vostra politica di restituzione in caso di problemi?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R: Se riscontrate un problema con la vostra cerniera, contattateci entro <strong>7 giorni<\/strong>. Gestiamo rapidamente sostituzioni o rimborsi per assicurarci che ogni cliente rimanga soddisfatto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>XG02-017 Cerniera per congelatori in acciaio inossidabile per impieghi gravosi, progettata per porte di celle frigorifere, pensata per garantire una durata estrema in ambienti a bassa temperatura e ad alta umidit\u00e0. La sua struttura rinforzata garantisce una capacit\u00e0 di carico superiore, resistenza alla corrosione e affidabilit\u00e0 a lungo termine: perfetta per celle frigorifere, impianti di lavorazione alimentare e camere fredde farmaceutiche. Codice Art. N. Materiale Trattamento superficiale XG02-017 XG02-017 SUS304 Specchiato D: Perch\u00e9 scegliere questa cerniera in acciaio inossidabile [\u2026]<\/p>","protected":false},"author":1,"featured_media":3448,"template":"","meta":{"_acf_changed":false,"_gspb_post_css":"","footnotes":""},"product_cat":[5],"product_tag":[],"class_list":["post-3439","wpkj_product","type-wpkj_product","status-publish","has-post-thumbnail","hentry","product_cat-cold-storage-hinges"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Stainless Steel Heavy-Duty Freezer Hinge for Cold Storage Doors - Hinges Manufacturer<\/title>\n<meta name=\"description\" content=\"stainless steel heavy-duty freezer hinge for cold storage doors\u2014strong, corrosion-resistant, and built for extreme conditions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stainless Steel Heavy-Duty Freezer Hinge for Cold Storage Doors - Hinges Manufacturer\" \/>\n<meta property=\"og:description\" content=\"stainless steel heavy-duty freezer hinge for cold storage doors\u2014strong, corrosion-resistant, and built for extreme conditions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/\" \/>\n<meta property=\"og:site_name\" content=\"Hinges Manufacturer\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T07:07:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-4.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/\",\"url\":\"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/\",\"name\":\"Stainless Steel Heavy-Duty Freezer Hinge for Cold Storage Doors - Hinges Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/hinges-htan.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-4.webp\",\"datePublished\":\"2025-10-14T08:06:14+00:00\",\"dateModified\":\"2025-12-17T07:07:14+00:00\",\"description\":\"stainless steel heavy-duty freezer hinge for cold storage doors\u2014strong, corrosion-resistant, and built for extreme conditions.\",\"breadcrumb\":{\"@id\":\"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hinges-htan.com\/product\/stainless-steel-heavy-duty-freezer-hinge-for-cold-storage-doors\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/#primaryimage\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-4.webp\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-4.webp\",\"width\":500,\"height\":500,\"caption\":\"XG02-017 Stainless Steel Heavy-Duty Freezer Hinge for Cold Storage Doors\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hinges-htan.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u4ea7\u54c1\",\"item\":\"https:\/\/hinges-htan.com\/it\/prodotti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stainless Steel Heavy-Duty Freezer Hinge for Cold Storage Doors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hinges-htan.com\/it\/#website\",\"url\":\"https:\/\/hinges-htan.com\/it\/\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"description\":\"Cabinet &amp; Enclosure Hinge Solutions\",\"publisher\":{\"@id\":\"https:\/\/hinges-htan.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hinges-htan.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hinges-htan.com\/it\/#organization\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"url\":\"https:\/\/hinges-htan.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/hinges-htan.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"width\":726,\"height\":172,\"caption\":\"HTAN Industrial Hinges Manufacturer\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cerniera per congelatore in acciaio inox per porte di celle frigorifere - Cerniere Fornitore","description":"cerniera per congelatore in acciaio inox per impieghi gravosi per le porte delle celle frigorifere: forte, resistente alla corrosione e costruita per condizioni estreme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/","og_locale":"it_IT","og_type":"article","og_title":"Stainless Steel Heavy-Duty Freezer Hinge for Cold Storage Doors - Hinges Manufacturer","og_description":"stainless steel heavy-duty freezer hinge for cold storage doors\u2014strong, corrosion-resistant, and built for extreme conditions.","og_url":"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/","og_site_name":"Hinges Manufacturer","article_modified_time":"2025-12-17T07:07:14+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-4.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/","url":"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/","name":"Cerniera per congelatore in acciaio inox per porte di celle frigorifere - Cerniere Fornitore","isPartOf":{"@id":"https:\/\/hinges-htan.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/#primaryimage"},"image":{"@id":"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/#primaryimage"},"thumbnailUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-4.webp","datePublished":"2025-10-14T08:06:14+00:00","dateModified":"2025-12-17T07:07:14+00:00","description":"cerniera per congelatore in acciaio inox per impieghi gravosi per le porte delle celle frigorifere: forte, resistente alla corrosione e costruita per condizioni estreme.","breadcrumb":{"@id":"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hinges-htan.com\/product\/stainless-steel-heavy-duty-freezer-hinge-for-cold-storage-doors\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/#primaryimage","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-4.webp","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-017-Stainless-Steel-Heavy-Duty-Freezer-Hinge-for-Cold-Storage-Doors-4.webp","width":500,"height":500,"caption":"XG02-017 Stainless Steel Heavy-Duty Freezer Hinge for Cold Storage Doors"},{"@type":"BreadcrumbList","@id":"https:\/\/hinges-htan.com\/it\/prodotto\/cerniera-per-congelatore-in-acciaio-inox-per-porte-per-celle-frigorifere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hinges-htan.com\/it\/"},{"@type":"ListItem","position":2,"name":"\u4ea7\u54c1","item":"https:\/\/hinges-htan.com\/it\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Stainless Steel Heavy-Duty Freezer Hinge for Cold Storage Doors"}]},{"@type":"WebSite","@id":"https:\/\/hinges-htan.com\/it\/#website","url":"https:\/\/hinges-htan.com\/it\/","name":"HTAN Produttore di cerniere industriali","description":"Soluzioni per cerniere di armadi e contenitori","publisher":{"@id":"https:\/\/hinges-htan.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hinges-htan.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/hinges-htan.com\/it\/#organization","name":"HTAN Produttore di cerniere industriali","url":"https:\/\/hinges-htan.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/hinges-htan.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","width":726,"height":172,"caption":"HTAN Industrial Hinges Manufacturer"},"image":{"@id":"https:\/\/hinges-htan.com\/it\/#\/schema\/logo\/image\/"}}]}},"acf":{"_product_image_gallery":[3445,3446,3447],"_product_excerpt":"Manufacturer: HTAN\r\nModel: XG02-017\r\nUnit Price: Get Latest Price\r\nMOQ: 1 Piece\r\nLead Time: In Stock (Ships within 24h) \/20-25 Days for Custom\r\nCustomization: OEM \/ ODM Support","post_download_file":3449},"_links":{"self":[{"href":"https:\/\/hinges-htan.com\/it\/wp-json\/wp\/v2\/wpkj_product\/3439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hinges-htan.com\/it\/wp-json\/wp\/v2\/wpkj_product"}],"about":[{"href":"https:\/\/hinges-htan.com\/it\/wp-json\/wp\/v2\/types\/wpkj_product"}],"author":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/it\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/hinges-htan.com\/it\/wp-json\/wp\/v2\/wpkj_product\/3439\/revisions"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/it\/wp-json\/wp\/v2\/media\/3447"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/it\/wp-json\/wp\/v2\/media\/3446"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/it\/wp-json\/wp\/v2\/media\/3445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/it\/wp-json\/wp\/v2\/media\/3448"}],"wp:attachment":[{"href":"https:\/\/hinges-htan.com\/it\/wp-json\/wp\/v2\/media?parent=3439"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hinges-htan.com\/it\/wp-json\/wp\/v2\/product_cat?post=3439"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hinges-htan.com\/it\/wp-json\/wp\/v2\/product_tag?post=3439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}