{"id":3,"count":19,"description":"As dobradi\u00e7as de eleva\u00e7\u00e3o, tamb\u00e9m conhecidas como dobradi\u00e7as de jun\u00e7\u00e3o deslizante, s\u00e3o dobradi\u00e7as utilizadas em aplica\u00e7\u00f5es que requerem manuten\u00e7\u00e3o frequente e remo\u00e7\u00e3o de pain\u00e9is de portas, tais como v\u00e1rias portas de arm\u00e1rios de equipamento industrial e portas de arm\u00e1rios.","link":"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/","name":"Dobradi\u00e7as de eleva\u00e7\u00e3o","slug":"dobradicas-de-elevacao","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lift-off hinges - Hinges Manufacturer<\/title>\n<meta name=\"description\" content=\"Lift-off hinges, also known as slip-joint hinges, are hinges used in applications that require frequent maintenance and removal of door panels, such as various industrial equipment cabinet doors and cabinet doors.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lift-off hinges - Hinges Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Lift-off hinges, also known as slip-joint hinges, are hinges used in applications that require frequent maintenance and removal of door panels, such as various industrial equipment cabinet doors and cabinet doors.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Hinges Manufacturer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/\",\"url\":\"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/\",\"name\":\"Lift-off hinges - Hinges Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/#website\"},\"description\":\"Lift-off hinges, also known as slip-joint hinges, are hinges used in applications that require frequent maintenance and removal of door panels, such as various industrial equipment cabinet doors and cabinet doors.\",\"breadcrumb\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/hinges-htan.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lift-off hinges\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/#website\",\"url\":\"https:\/\/hinges-htan.com\/pt\/\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"description\":\"Cabinet &amp; Enclosure Hinge Solutions\",\"publisher\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hinges-htan.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/#organization\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"url\":\"https:\/\/hinges-htan.com\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"width\":726,\"height\":172,\"caption\":\"HTAN Industrial Hinges Manufacturer\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lift-off hinges - Hinges Manufacturer","description":"As dobradi\u00e7as de eleva\u00e7\u00e3o, tamb\u00e9m conhecidas como dobradi\u00e7as de jun\u00e7\u00e3o deslizante, s\u00e3o dobradi\u00e7as utilizadas em aplica\u00e7\u00f5es que requerem manuten\u00e7\u00e3o frequente e remo\u00e7\u00e3o de pain\u00e9is de portas, tais como v\u00e1rias portas de arm\u00e1rios de equipamento industrial e portas de arm\u00e1rios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/","og_locale":"pt_PT","og_type":"article","og_title":"Lift-off hinges - Hinges Manufacturer","og_description":"Lift-off hinges, also known as slip-joint hinges, are hinges used in applications that require frequent maintenance and removal of door panels, such as various industrial equipment cabinet doors and cabinet doors.","og_url":"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/","og_site_name":"Hinges Manufacturer","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/","url":"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/","name":"Dobradi\u00e7as de eleva\u00e7\u00e3o - Dobradi\u00e7as Fabricante","isPartOf":{"@id":"https:\/\/hinges-htan.com\/pt\/#website"},"description":"As dobradi\u00e7as de eleva\u00e7\u00e3o, tamb\u00e9m conhecidas como dobradi\u00e7as de jun\u00e7\u00e3o deslizante, s\u00e3o dobradi\u00e7as utilizadas em aplica\u00e7\u00f5es que requerem manuten\u00e7\u00e3o frequente e remo\u00e7\u00e3o de pain\u00e9is de portas, tais como v\u00e1rias portas de arm\u00e1rios de equipamento industrial e portas de arm\u00e1rios.","breadcrumb":{"@id":"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/hinges-htan.com\/pt\/categoria-do-produto\/dobradicas-de-elevacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/hinges-htan.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Lift-off hinges"}]},{"@type":"WebSite","@id":"https:\/\/hinges-htan.com\/pt\/#website","url":"https:\/\/hinges-htan.com\/pt\/","name":"HTAN Dobradi\u00e7as Industriais Fabricante","description":"Solu\u00e7\u00f5es de dobradi\u00e7as para arm\u00e1rios e gabinetes","publisher":{"@id":"https:\/\/hinges-htan.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hinges-htan.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/hinges-htan.com\/pt\/#organization","name":"HTAN Dobradi\u00e7as Industriais Fabricante","url":"https:\/\/hinges-htan.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","width":726,"height":172,"caption":"HTAN Industrial Hinges Manufacturer"},"image":{"@id":"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/product_cat\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/wpkj_product?product_cat=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}