{"id":2800,"date":"2025-09-27T05:41:59","date_gmt":"2025-09-27T05:41:59","guid":{"rendered":"https:\/\/hinges-htan.com\/?post_type=wpkj_product&#038;p=2800"},"modified":"2025-12-18T01:53:43","modified_gmt":"2025-12-18T01:53:43","slug":"dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado","status":"publish","type":"wpkj_product","link":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/","title":{"rendered":"Dobradi\u00e7a amov\u00edvel oculta | A\u00e7o inoxid\u00e1vel ou ferro galvanizado"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A dobradi\u00e7a oculta amov\u00edvel XG02-055 (comprimento total: 48 mm) apresenta um design compacto e duradouro concebido para aplica\u00e7\u00f5es industriais. A sua remo\u00e7\u00e3o sem ferramentas permite a separa\u00e7\u00e3o r\u00e1pida do painel da porta para uma cablagem, manuten\u00e7\u00e3o e transporte convenientes. Constru\u00edda em a\u00e7o inoxid\u00e1vel para resist\u00eancia \u00e0 corros\u00e3o ou em ferro galvanizado para poupan\u00e7a de custos, suporta um \u00e2ngulo de abertura de 110\u00b0 para uma opera\u00e7\u00e3o f\u00e1cil. Adequado para arm\u00e1rios de controlo, caixas de automa\u00e7\u00e3o, equipamento de laborat\u00f3rio e arm\u00e1rios de telecomunica\u00e7\u00f5es.<\/p>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-1fac9c7\" class=\"gspb_heading gspb_heading-id-gsbp-1fac9c7\">Desenho dimensional<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"570\" src=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-HingeDimension-Drawing-1024x570.webp\" alt=\"XG02-055 Dobradi\u00e7a amov\u00edvel ocultaDesenho dimensional\" class=\"wp-image-2802\" srcset=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-HingeDimension-Drawing-1024x570.webp 1024w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-HingeDimension-Drawing-300x167.webp 300w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-HingeDimension-Drawing-768x427.webp 768w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-HingeDimension-Drawing-18x10.webp 18w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-HingeDimension-Drawing.webp 1042w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">C\u00f3digo<\/td><td class=\"has-text-align-center\" data-align=\"center\">Item No.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Material<\/td><td class=\"has-text-align-center\" data-align=\"center\">Tratamento de superf\u00edcie<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">XG02-055<\/td><td class=\"has-text-align-center\" data-align=\"center\">XG02-055<\/td><td class=\"has-text-align-center\" data-align=\"center\">SPCC<\/td><td class=\"has-text-align-center\" data-align=\"center\">Galvanizado<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">XG02-055S<\/td><td class=\"has-text-align-center\" data-align=\"center\">SUS304<\/td><td class=\"has-text-align-center\" data-align=\"center\">Acabamento vibrat\u00f3rio<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-d6e2352\" class=\"gspb_heading gspb_heading-id-gsbp-d6e2352\">FAQ<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: Como instalar a dobradi\u00e7a amov\u00edvel oculta de 48 mm?<\/strong><br><strong>A:<\/strong> A instala\u00e7\u00e3o \u00e9 r\u00e1pida e segura utilizando parafusos de cabe\u00e7a escareada M8 em arm\u00e1rios de controlo ou caixas. O seu design amov\u00edvel permite a remo\u00e7\u00e3o do painel da porta sem ferramentas, tornando a manuten\u00e7\u00e3o e a cablagem mais convenientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: O tamanho ou o acabamento da superf\u00edcie desta dobradi\u00e7a oculta pode ser personalizado?<\/strong><br><strong>A:<\/strong> Sim, a personaliza\u00e7\u00e3o est\u00e1 dispon\u00edvel. Fornecemos servi\u00e7os OEM com op\u00e7\u00f5es como a\u00e7o inoxid\u00e1vel resistente \u00e0 corros\u00e3o ou ferro galvanizado econ\u00f3mico, juntamente com v\u00e1rios tratamentos de superf\u00edcie para satisfazer diferentes necessidades de aplica\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q: Onde est\u00e1 localizada a f\u00e1brica de dobradi\u00e7as e qual \u00e9 a capacidade de produ\u00e7\u00e3o?<\/strong><br><strong>A:<\/strong> A nossa f\u00e1brica est\u00e1 localizada na cidade de Dongguan, prov\u00edncia de Guangdong, no cora\u00e7\u00e3o do centro de produ\u00e7\u00e3o da China. Com maquinaria avan\u00e7ada e sistemas de controlo de qualidade rigorosos, apoiamos a produ\u00e7\u00e3o de dobradi\u00e7as em grande escala. Tamb\u00e9m aceitamos visitas \u00e0 f\u00e1brica para discutir oportunidades de personaliza\u00e7\u00e3o e parceria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: Quanto tempo demora a expedi\u00e7\u00e3o ap\u00f3s a encomenda de dobradi\u00e7as ocultas amov\u00edveis?<\/strong><br><strong>A:<\/strong> Para os modelos padr\u00e3o, enviamos diretamente do stock para garantir uma entrega r\u00e1pida. As encomendas personalizadas s\u00e3o produzidas com prazos de entrega eficientes, apoiados por uma log\u00edstica global fi\u00e1vel para envios atempados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: Qual \u00e9 a vossa pol\u00edtica de devolu\u00e7\u00e3o se as dobradi\u00e7as n\u00e3o cumprirem os requisitos?<\/strong><br><strong>A:<\/strong> Seguimos uma pol\u00edtica de devolu\u00e7\u00e3o que coloca o cliente em primeiro lugar. Se receber artigos defeituosos, danificados ou incompat\u00edveis, oferecemos devolu\u00e7\u00f5es ou substitui\u00e7\u00f5es sem problemas para garantir a sua total satisfa\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>A dobradi\u00e7a oculta amov\u00edvel XG02-055 (comprimento total: 48 mm) apresenta um design compacto e duradouro concebido para aplica\u00e7\u00f5es industriais. A sua remo\u00e7\u00e3o sem ferramentas permite a separa\u00e7\u00e3o r\u00e1pida do painel da porta para uma cablagem, manuten\u00e7\u00e3o e transporte convenientes. Constru\u00edda em a\u00e7o inoxid\u00e1vel para resist\u00eancia \u00e0 corros\u00e3o ou em ferro galvanizado para poupan\u00e7a de custos, suporta um \u00e2ngulo de abertura de 110\u00b0 para uma opera\u00e7\u00e3o f\u00e1cil. Adequado para controlo [...]<\/p>","protected":false},"author":1,"featured_media":2835,"template":"","meta":{"_acf_changed":false,"_gspb_post_css":"","footnotes":""},"product_cat":[7],"product_tag":[],"class_list":["post-2800","wpkj_product","type-wpkj_product","status-publish","has-post-thumbnail","hentry","product_cat-concealed-hinges"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Removable Concealed Hinge | Stainless Steel or Galvanized Iron - Hinges Manufacturer<\/title>\n<meta name=\"description\" content=\"Removable Concealed Hinge (48mm total length): compact, durable stainless steel\/galvanized iron build for industrial use.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Removable Concealed Hinge | Stainless Steel or Galvanized Iron - Hinges Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Removable Concealed Hinge (48mm total length): compact, durable stainless steel\/galvanized iron build for industrial use.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/\" \/>\n<meta property=\"og:site_name\" content=\"Hinges Manufacturer\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T01:53:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-Hinge.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"502\" \/>\n\t<meta property=\"og:image:height\" content=\"501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/\",\"url\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/\",\"name\":\"Removable Concealed Hinge | Stainless Steel or Galvanized Iron - Hinges Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-Hinge.webp\",\"datePublished\":\"2025-09-27T05:41:59+00:00\",\"dateModified\":\"2025-12-18T01:53:43+00:00\",\"description\":\"Removable Concealed Hinge (48mm total length): compact, durable stainless steel\/galvanized iron build for industrial use.\",\"breadcrumb\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hinges-htan.com\/product\/removable-concealed-hinge-48mm-stainless-steel-or-galvanized-iron\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/#primaryimage\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-Hinge.webp\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-Hinge.webp\",\"width\":502,\"height\":501,\"caption\":\"XG02-055 Removable Concealed Hinge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/hinges-htan.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u4ea7\u54c1\",\"item\":\"https:\/\/hinges-htan.com\/pt\/produtos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Removable Concealed Hinge | Stainless Steel or Galvanized Iron\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/#website\",\"url\":\"https:\/\/hinges-htan.com\/pt\/\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"description\":\"Cabinet &amp; Enclosure Hinge Solutions\",\"publisher\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hinges-htan.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/#organization\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"url\":\"https:\/\/hinges-htan.com\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"width\":726,\"height\":172,\"caption\":\"HTAN Industrial Hinges Manufacturer\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dobradi\u00e7a amov\u00edvel oculta | A\u00e7o inoxid\u00e1vel ou ferro galvanizado - Dobradi\u00e7as Fabricante","description":"Dobradi\u00e7a oculta amov\u00edvel (48 mm de comprimento total): constru\u00e7\u00e3o compacta e duradoura em a\u00e7o inoxid\u00e1vel\/ferro galvanizado para utiliza\u00e7\u00e3o industrial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/","og_locale":"pt_PT","og_type":"article","og_title":"Removable Concealed Hinge | Stainless Steel or Galvanized Iron - Hinges Manufacturer","og_description":"Removable Concealed Hinge (48mm total length): compact, durable stainless steel\/galvanized iron build for industrial use.","og_url":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/","og_site_name":"Hinges Manufacturer","article_modified_time":"2025-12-18T01:53:43+00:00","og_image":[{"width":502,"height":501,"url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-Hinge.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/","url":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/","name":"Dobradi\u00e7a amov\u00edvel oculta | A\u00e7o inoxid\u00e1vel ou ferro galvanizado - Dobradi\u00e7as Fabricante","isPartOf":{"@id":"https:\/\/hinges-htan.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/#primaryimage"},"image":{"@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/#primaryimage"},"thumbnailUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-Hinge.webp","datePublished":"2025-09-27T05:41:59+00:00","dateModified":"2025-12-18T01:53:43+00:00","description":"Dobradi\u00e7a oculta amov\u00edvel (48 mm de comprimento total): constru\u00e7\u00e3o compacta e duradoura em a\u00e7o inoxid\u00e1vel\/ferro galvanizado para utiliza\u00e7\u00e3o industrial.","breadcrumb":{"@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hinges-htan.com\/product\/removable-concealed-hinge-48mm-stainless-steel-or-galvanized-iron\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/#primaryimage","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-Hinge.webp","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/09\/XG02-055-Removable-Concealed-Hinge.webp","width":502,"height":501,"caption":"XG02-055 Removable Concealed Hinge"},{"@type":"BreadcrumbList","@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-amovivel-oculta-48mm-aco-inoxidavel-ou-ferro-galvanizado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/hinges-htan.com\/pt\/"},{"@type":"ListItem","position":2,"name":"\u4ea7\u54c1","item":"https:\/\/hinges-htan.com\/pt\/produtos\/"},{"@type":"ListItem","position":3,"name":"Removable Concealed Hinge | Stainless Steel or Galvanized Iron"}]},{"@type":"WebSite","@id":"https:\/\/hinges-htan.com\/pt\/#website","url":"https:\/\/hinges-htan.com\/pt\/","name":"HTAN Dobradi\u00e7as Industriais Fabricante","description":"Solu\u00e7\u00f5es de dobradi\u00e7as para arm\u00e1rios e gabinetes","publisher":{"@id":"https:\/\/hinges-htan.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hinges-htan.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/hinges-htan.com\/pt\/#organization","name":"HTAN Dobradi\u00e7as Industriais Fabricante","url":"https:\/\/hinges-htan.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","width":726,"height":172,"caption":"HTAN Industrial Hinges Manufacturer"},"image":{"@id":"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/"}}]}},"acf":{"_product_image_gallery":[2836,2838,2837],"_product_excerpt":"Manufacturer: HTAN\r\nModel: XG02-055\r\nUnit Price: Get Latest Price\r\nMOQ: 1 Piece\r\nLead Time: In Stock (Ships within 24h) \/20-25 Days for Custom\r\nCustomization: OEM \/ ODM Support","post_download_file":2840},"_links":{"self":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/wpkj_product\/2800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/wpkj_product"}],"about":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/types\/wpkj_product"}],"author":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/wpkj_product\/2800\/revisions"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/2837"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/2838"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/2836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/2835"}],"wp:attachment":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media?parent=2800"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/product_cat?post=2800"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/product_tag?post=2800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}