{"id":3398,"date":"2025-10-14T02:41:07","date_gmt":"2025-10-14T02:41:07","guid":{"rendered":"https:\/\/hinges-htan.com\/?post_type=wpkj_product&#038;p=3398"},"modified":"2025-12-17T07:14:13","modified_gmt":"2025-12-17T07:14:13","slug":"dobradica-para-camaras-frigorificas","status":"publish","type":"wpkj_product","link":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/","title":{"rendered":"Dobradi\u00e7a de refrigera\u00e7\u00e3o resistente para c\u00e2maras frigor\u00edficas e congeladores"},"content":{"rendered":"<p class=\"wp-block-paragraph\">XG02-084 Dobradi\u00e7a para c\u00e2maras frigor\u00edficas para trabalhos pesados, concebida para uma resist\u00eancia e durabilidade superiores em ambientes de baixa temperatura. Fabricada em a\u00e7o inoxid\u00e1vel ou liga de zinco, resiste \u00e0 corros\u00e3o, \u00e0 congela\u00e7\u00e3o e ao desgaste - ideal para arcas congeladoras, f\u00e1bricas de processamento de alimentos e frigor\u00edficos comerciais. Garante uma veda\u00e7\u00e3o estanque, um desempenho fi\u00e1vel e uma longa vida \u00fatil.<\/p>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-3f6a4fa\" class=\"gspb_heading gspb_heading-id-gsbp-3f6a4fa\">Desenho dimensional<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1017\" height=\"614\" src=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-Dimension-Drawing.webp\" alt=\"XG02-084 Dobradi\u00e7a resistente para c\u00e2maras frigor\u00edficas Desenho dimensional\" class=\"wp-image-3399\" srcset=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-Dimension-Drawing.webp 1017w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-Dimension-Drawing-300x181.webp 300w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-Dimension-Drawing-768x464.webp 768w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-Dimension-Drawing-18x12.webp 18w\" sizes=\"auto, (max-width: 1017px) 100vw, 1017px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">C\u00f3digo<\/td><td class=\"has-text-align-center\" data-align=\"center\">Item No.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Material<\/td><td class=\"has-text-align-center\" data-align=\"center\">Tratamento de superf\u00edcie<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">XG02-084<\/td><td class=\"has-text-align-center\" data-align=\"center\">XG02-084S<\/td><td class=\"has-text-align-center\" data-align=\"center\">SUS304<\/td><td class=\"has-text-align-center\" data-align=\"center\">Espelho<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">XG02-084<\/td><td class=\"has-text-align-center\" data-align=\"center\">ZDC<\/td><td class=\"has-text-align-center\" data-align=\"center\">Cromado<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-6c77b2e\" class=\"gspb_heading gspb_heading-id-gsbp-6c77b2e\">FAQ<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"q-does-your-factory-provide-r-d-support-for-cold-storage-hinges\"><strong>Q: A vossa f\u00e1brica fornece apoio de I&amp;D para dobradi\u00e7as de c\u00e2maras frigor\u00edficas?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A:Sim! A nossa f\u00e1brica tem uma equipa de I&amp;D experiente, especializada na conce\u00e7\u00e3o de dobradi\u00e7as para trabalhos pesados. Melhoramos continuamente os materiais e estruturas para garantir um desempenho superior em ambientes de baixa temperatura e alta frequ\u00eancia de utiliza\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"q-can-i-request-customized-cold-storage-hinges-for-my-project\"><strong>Q:Posso solicitar dobradi\u00e7as para c\u00e2maras frigor\u00edficas personalizadas para o meu projeto?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A:Sem d\u00favida. Oferecemos a personaliza\u00e7\u00e3o de dobradi\u00e7as com base no tamanho, peso, material e aplica\u00e7\u00e3o da sua porta. Quer necessite de dobradi\u00e7as de a\u00e7o inoxid\u00e1vel ou de liga de zinco, os nossos engenheiros podem adaptar a melhor solu\u00e7\u00e3o para o seu sistema de armazenamento a frio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"q-are-you-a-manufacturer-or-a-trading-company\"><strong>Q:\u00c9 um fabricante ou uma empresa comercial?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R:Somos um fabricante direto de dobradi\u00e7as com a nossa pr\u00f3pria f\u00e1brica de produ\u00e7\u00e3o. Isto permite-nos controlar a qualidade, oferecer pre\u00e7os competitivos e apoiar encomendas OEM e ODM para clientes globais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"q-how-long-does-shipping-take-after-placing-an-order\"><strong>P: Quanto tempo demora a expedi\u00e7\u00e3o ap\u00f3s a realiza\u00e7\u00e3o de uma encomenda?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R:Enviamos as encomendas com rapidez. Dobradi\u00e7as de armazenamento a frio em stock. Envio dentro de 24 horas.enquanto as dobradi\u00e7as personalizadas podem demorar um pouco mais, dependendo das especifica\u00e7\u00f5es e da quantidade do pedido.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"q-what-is-your-return-or-replacement-policy\"><strong>P: Qual \u00e9 a vossa pol\u00edtica de devolu\u00e7\u00e3o ou substitui\u00e7\u00e3o?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">R: A satisfa\u00e7\u00e3o do cliente \u00e9 a nossa prioridade. Se receber uma dobradi\u00e7a defeituosa ou incompat\u00edvel, contacte-nos no prazo de 7 dias ap\u00f3s a entrega - providenciaremos uma substitui\u00e7\u00e3o r\u00e1pida ou um reembolso ap\u00f3s verifica\u00e7\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"<p>XG02-084 Dobradi\u00e7a para c\u00e2maras frigor\u00edficas de alta resist\u00eancia, concebida para oferecer resist\u00eancia e durabilidade superiores em ambientes de baixa temperatura. Fabricada em a\u00e7o inoxid\u00e1vel ou liga de zinco, resiste \u00e0 corros\u00e3o, ao congelamento e ao desgaste \u2014 ideal para c\u00e2maras frigor\u00edficas, f\u00e1bricas de processamento alimentar e frigor\u00edficos comerciais. Garante uma veda\u00e7\u00e3o herm\u00e9tica, um desempenho fi\u00e1vel e uma longa vida \u00fatil. C\u00f3digo N.\u00ba do artigo Material Tratamento de superf\u00edcie XG02-084 XG02-084S SUS304 Espelhado [\u2026]<\/p>","protected":false},"author":1,"featured_media":3400,"template":"","meta":{"_acf_changed":false,"_gspb_post_css":"","footnotes":""},"product_cat":[5],"product_tag":[],"class_list":["post-3398","wpkj_product","type-wpkj_product","status-publish","has-post-thumbnail","hentry","product_cat-cold-storage-hinges"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Heavy-Duty Refrigeration Hinge for Cold Rooms &amp; Freezers - Hinges Manufacturer<\/title>\n<meta name=\"description\" content=\"Heavy-duty cold storage hinge for freezers and food plants. Corrosion-resistant, anti-freezing, and built for long-lasting performance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Heavy-Duty Refrigeration Hinge for Cold Rooms &amp; Freezers - Hinges Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Heavy-duty cold storage hinge for freezers and food plants. Corrosion-resistant, anti-freezing, and built for long-lasting performance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/\" \/>\n<meta property=\"og:site_name\" content=\"Hinges Manufacturer\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T07:14:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"502\" \/>\n\t<meta property=\"og:image:height\" content=\"501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/\",\"url\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/\",\"name\":\"Heavy-Duty Refrigeration Hinge for Cold Rooms &amp; Freezers - Hinges Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-2.webp\",\"datePublished\":\"2025-10-14T02:41:07+00:00\",\"dateModified\":\"2025-12-17T07:14:13+00:00\",\"description\":\"Heavy-duty cold storage hinge for freezers and food plants. Corrosion-resistant, anti-freezing, and built for long-lasting performance.\",\"breadcrumb\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hinges-htan.com\/product\/heavy-duty-cold-storage-hinge\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/#primaryimage\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-2.webp\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-2.webp\",\"width\":502,\"height\":501,\"caption\":\"XG02-084 Heavy-duty cold storage hinge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/hinges-htan.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u4ea7\u54c1\",\"item\":\"https:\/\/hinges-htan.com\/pt\/produtos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Heavy-Duty Refrigeration Hinge for Cold Rooms &amp; Freezers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/#website\",\"url\":\"https:\/\/hinges-htan.com\/pt\/\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"description\":\"Cabinet &amp; Enclosure Hinge Solutions\",\"publisher\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hinges-htan.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/#organization\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"url\":\"https:\/\/hinges-htan.com\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"width\":726,\"height\":172,\"caption\":\"HTAN Industrial Hinges Manufacturer\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dobradi\u00e7a de refrigera\u00e7\u00e3o para c\u00e2maras frigor\u00edficas e congeladores - Fabricante de Dobradi\u00e7as","description":"Dobradi\u00e7a de armazenamento a frio resistente para congeladores e instala\u00e7\u00f5es alimentares. Resistente \u00e0 corros\u00e3o, anti-congela\u00e7\u00e3o e constru\u00edda para um desempenho duradouro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/","og_locale":"pt_PT","og_type":"article","og_title":"Heavy-Duty Refrigeration Hinge for Cold Rooms &amp; Freezers - Hinges Manufacturer","og_description":"Heavy-duty cold storage hinge for freezers and food plants. Corrosion-resistant, anti-freezing, and built for long-lasting performance.","og_url":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/","og_site_name":"Hinges Manufacturer","article_modified_time":"2025-12-17T07:14:13+00:00","og_image":[{"width":502,"height":501,"url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-2.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/","url":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/","name":"Dobradi\u00e7a de refrigera\u00e7\u00e3o para c\u00e2maras frigor\u00edficas e congeladores - Fabricante de Dobradi\u00e7as","isPartOf":{"@id":"https:\/\/hinges-htan.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/#primaryimage"},"image":{"@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/#primaryimage"},"thumbnailUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-2.webp","datePublished":"2025-10-14T02:41:07+00:00","dateModified":"2025-12-17T07:14:13+00:00","description":"Dobradi\u00e7a de armazenamento a frio resistente para congeladores e instala\u00e7\u00f5es alimentares. Resistente \u00e0 corros\u00e3o, anti-congela\u00e7\u00e3o e constru\u00edda para um desempenho duradouro.","breadcrumb":{"@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hinges-htan.com\/product\/heavy-duty-cold-storage-hinge\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/#primaryimage","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-2.webp","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/XG02-084-Heavy-duty-cold-storage-hinge-2.webp","width":502,"height":501,"caption":"XG02-084 Heavy-duty cold storage hinge"},{"@type":"BreadcrumbList","@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-para-camaras-frigorificas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/hinges-htan.com\/pt\/"},{"@type":"ListItem","position":2,"name":"\u4ea7\u54c1","item":"https:\/\/hinges-htan.com\/pt\/produtos\/"},{"@type":"ListItem","position":3,"name":"Heavy-Duty Refrigeration Hinge for Cold Rooms &amp; Freezers"}]},{"@type":"WebSite","@id":"https:\/\/hinges-htan.com\/pt\/#website","url":"https:\/\/hinges-htan.com\/pt\/","name":"HTAN Dobradi\u00e7as Industriais Fabricante","description":"Solu\u00e7\u00f5es de dobradi\u00e7as para arm\u00e1rios e gabinetes","publisher":{"@id":"https:\/\/hinges-htan.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hinges-htan.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/hinges-htan.com\/pt\/#organization","name":"HTAN Dobradi\u00e7as Industriais Fabricante","url":"https:\/\/hinges-htan.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","width":726,"height":172,"caption":"HTAN Industrial Hinges Manufacturer"},"image":{"@id":"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/"}}]}},"acf":{"_product_image_gallery":[3401,3402,3403,3404,3405,3406,3407],"_product_excerpt":"Manufacturer: HTAN\r\nModel: XG02-084\r\nUnit Price: Get Latest Price\r\nMOQ: 1 Piece\r\nLead Time: In Stock (Ships within 24h) \/20-25 Days for Custom\r\nCustomization: OEM \/ ODM Support","post_download_file":3408},"_links":{"self":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/wpkj_product\/3398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/wpkj_product"}],"about":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/types\/wpkj_product"}],"author":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/wpkj_product\/3398\/revisions"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3407"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3406"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3405"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3404"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3403"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3402"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3400"}],"wp:attachment":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media?parent=3398"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/product_cat?post=3398"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/product_tag?post=3398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}