{"id":3851,"date":"2025-10-22T06:50:15","date_gmt":"2025-10-22T06:50:15","guid":{"rendered":"https:\/\/hinges-htan.com\/?post_type=wpkj_product&#038;p=3851"},"modified":"2025-12-17T05:44:56","modified_gmt":"2025-12-17T05:44:56","slug":"dobradica-de-binario-de-plastico-ajustavel","status":"publish","type":"wpkj_product","link":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/","title":{"rendered":"Dobradi\u00e7a pl\u00e1stica ajust\u00e1vel de torque - Leve, silenciosa e dur\u00e1vel"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A dobradi\u00e7a de bin\u00e1rio de pl\u00e1stico ajust\u00e1vel (PA6, 270\u00b0) oferece um movimento suave e silencioso e uma tens\u00e3o personaliz\u00e1vel. Leve, resistente \u00e0 corros\u00e3o e dispon\u00edvel em preto ou branco - ideal para dispositivos dom\u00e9sticos inteligentes, pequenos electrodom\u00e9sticos, interiores de autom\u00f3veis, equipamento m\u00e9dico e produtos de escrit\u00f3rio.<\/p>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-52fec14\" class=\"gspb_heading gspb_heading-id-gsbp-52fec14\">Desenho dimensional<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"557\" src=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-Dimension-Drawing-1024x557.webp\" alt=\"Dobradi\u00e7a de bin\u00e1rio de pl\u00e1stico ajust\u00e1vel Desenho dimensional\" class=\"wp-image-3852\" srcset=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-Dimension-Drawing-1024x557.webp 1024w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-Dimension-Drawing-300x163.webp 300w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-Dimension-Drawing-768x418.webp 768w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-Dimension-Drawing-18x10.webp 18w, https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-Dimension-Drawing.webp 1046w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">C\u00f3digo<\/td><td class=\"has-text-align-center\" data-align=\"center\">Item No.<\/td><td class=\"has-text-align-center\" data-align=\"center\">Bin\u00e1rio N-m<\/td><td class=\"has-text-align-center\" data-align=\"center\">Bin\u00e1rio kgf-cm<\/td><td class=\"has-text-align-center\" data-align=\"center\">L<\/td><td class=\"has-text-align-center\" data-align=\"center\">W<\/td><td class=\"has-text-align-center\" data-align=\"center\">H<\/td><td class=\"has-text-align-center\" data-align=\"center\">t<\/td><td class=\"has-text-align-center\" data-align=\"center\">P1<\/td><td class=\"has-text-align-center\" data-align=\"center\">P2<\/td><td class=\"has-text-align-center\" data-align=\"center\">D<\/td><td class=\"has-text-align-center\" data-align=\"center\">M<\/td><td class=\"has-text-align-center\" data-align=\"center\">Material<\/td><td class=\"has-text-align-center\" data-align=\"center\">Tratamento de superf\u00edcie<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">XG11-061<\/td><td class=\"has-text-align-center\" data-align=\"center\">XG11-061-1<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">0-0.8<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">0-8<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">43<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">36.5<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">12.7<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">5.2<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">25.5<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">31.7<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">4.2<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">M5<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"4\">PA6<\/td><td class=\"has-text-align-center\" data-align=\"center\">Preto<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">XG11-061-2<\/td><td class=\"has-text-align-center\" data-align=\"center\">Branco<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">XG11-062<\/td><td class=\"has-text-align-center\" data-align=\"center\">XG11-062-1<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">0~4<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">0-40<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">63.5<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">57.5<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">19.5<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">38<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">47.5<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">6.5<\/td><td class=\"has-text-align-center\" data-align=\"center\" rowspan=\"2\">M6<\/td><td class=\"has-text-align-center\" data-align=\"center\">Preto<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">XG11-062-2<\/td><td class=\"has-text-align-center\" data-align=\"center\">Branco<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-2040ca2\" class=\"gspb_heading gspb_heading-id-gsbp-2040ca2\">FAQ<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: O que torna esta dobradi\u00e7a de bin\u00e1rio de pl\u00e1stico ajust\u00e1vel \u00fanica?<\/strong><br>R:Este <strong>Dobradi\u00e7a de bin\u00e1rio ajust\u00e1vel PA6 (270\u00b0)<\/strong> proporciona um movimento suave e silencioso e uma resist\u00eancia ajust\u00e1vel para um posicionamento preciso. \u00c9 leve, resistente \u00e0 corros\u00e3o e n\u00e3o risca - perfeito para <strong>dispositivos dom\u00e9sticos inteligentes, pequenos electrodom\u00e9sticos, instrumentos m\u00e9dicos e interiores de autom\u00f3veis<\/strong> que exigem um desempenho silencioso e duradouro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: Posso personalizar o tamanho, o bin\u00e1rio ou a cor da dobradi\u00e7a?<\/strong><br>R:Sim! N\u00f3s oferecemos <strong>solu\u00e7\u00f5es de dobradi\u00e7as personalizadas<\/strong> adaptados \u00e0 conce\u00e7\u00e3o do seu produto. As op\u00e7\u00f5es incluem <strong>ajuste do bin\u00e1rio, dimens\u00f5es de montagem e personaliza\u00e7\u00e3o da cor<\/strong> (padr\u00e3o preto ou branco). A nossa equipa de I&amp;D tamb\u00e9m pode prestar assist\u00eancia em projectos OEM\/ODM para corresponder perfeitamente \u00e0 sua aplica\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q:\u00c9 uma f\u00e1brica direta ou uma empresa comercial?<\/strong><br>R:Somos uma <strong>fabricante direto da f\u00e1brica<\/strong> com mais de 10 anos de experi\u00eancia na produ\u00e7\u00e3o de dobradi\u00e7as de bin\u00e1rio de precis\u00e3o. Todas as dobradi\u00e7as s\u00e3o fabricadas internamente utilizando <strong>Materiais PA6<\/strong> e s\u00e3o submetidos a rigorosos testes de bin\u00e1rio e durabilidade antes da expedi\u00e7\u00e3o para garantir um desempenho consistente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: Com que rapidez podem entregar a minha encomenda?<\/strong><br>R:As dobradi\u00e7as de torque padr\u00e3o est\u00e3o em stock e s\u00e3o enviadas no prazo de 24 horas. Para projectos personalizados, a produ\u00e7\u00e3o demora normalmente <strong>20-25 dias<\/strong>dependendo da quantidade e das especifica\u00e7\u00f5es da encomenda. Oferecemos <strong>transporte expresso global e transporte a granel<\/strong> para garantir a entrega atempada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P: Qual \u00e9 a vossa pol\u00edtica de devolu\u00e7\u00e3o ou substitui\u00e7\u00e3o?<\/strong><br>R:Fornecemos um <strong>Garantia de devolu\u00e7\u00e3o e substitui\u00e7\u00e3o de 30 dias<\/strong>. Se a dobradi\u00e7a tiver algum problema de qualidade ou n\u00e3o corresponder \u00e0s suas especifica\u00e7\u00f5es, a nossa equipa de apoio providenciar\u00e1 rapidamente uma <strong>reembolso ou substitui\u00e7\u00e3o<\/strong>garantindo uma experi\u00eancia de compra tranquila e fi\u00e1vel.<\/p>","protected":false},"excerpt":{"rendered":"<p>A dobradi\u00e7a de bin\u00e1rio de pl\u00e1stico ajust\u00e1vel (PA6, 270\u00b0) oferece um movimento suave e silencioso e uma tens\u00e3o personaliz\u00e1vel. Leve, resistente \u00e0 corros\u00e3o e dispon\u00edvel em preto ou branco - ideal para dispositivos dom\u00e9sticos inteligentes, pequenos electrodom\u00e9sticos, interiores de autom\u00f3veis, equipamento m\u00e9dico e produtos de escrit\u00f3rio. C\u00f3digo Item N.\u00ba Bin\u00e1rio N-m Bin\u00e1rio kgf-cm L L W H t P1 P2 D M Material Tratamento de superf\u00edcie XG11-061 XG11-061-1 0-0.8 [...]<\/p>","protected":false},"author":1,"featured_media":3859,"template":"","meta":{"_acf_changed":false,"_gspb_post_css":"","footnotes":""},"product_cat":[4],"product_tag":[],"class_list":["post-3851","wpkj_product","type-wpkj_product","status-publish","has-post-thumbnail","hentry","product_cat-torque-hinges"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Adjustable Plastic Torque Hinge \u2014 Lightweight, Quiet &amp; Durable - Hinges Manufacturer<\/title>\n<meta name=\"description\" content=\"Adjustable plastic torque hinge (PA6, 270\u00b0) delivers smooth, quiet motion and durability\u2014perfect for smart home and medical devices.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adjustable Plastic Torque Hinge \u2014 Lightweight, Quiet &amp; Durable - Hinges Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Adjustable plastic torque hinge (PA6, 270\u00b0) delivers smooth, quiet motion and durability\u2014perfect for smart home and medical devices.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/\" \/>\n<meta property=\"og:site_name\" content=\"Hinges Manufacturer\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T05:44:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-7.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/\",\"url\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/\",\"name\":\"Adjustable Plastic Torque Hinge \u2014 Lightweight, Quiet &amp; Durable - Hinges Manufacturer\",\"isPartOf\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-7.webp\",\"datePublished\":\"2025-10-22T06:50:15+00:00\",\"dateModified\":\"2025-12-17T05:44:56+00:00\",\"description\":\"Adjustable plastic torque hinge (PA6, 270\u00b0) delivers smooth, quiet motion and durability\u2014perfect for smart home and medical devices.\",\"breadcrumb\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hinges-htan.com\/product\/adjustable-plastic-torque-hinge\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/#primaryimage\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-7.webp\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-7.webp\",\"width\":500,\"height\":500,\"caption\":\"Adjustable plastic torque hinge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/hinges-htan.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u4ea7\u54c1\",\"item\":\"https:\/\/hinges-htan.com\/pt\/produtos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adjustable Plastic Torque Hinge \u2014 Lightweight, Quiet &amp; Durable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/#website\",\"url\":\"https:\/\/hinges-htan.com\/pt\/\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"description\":\"Cabinet &amp; Enclosure Hinge Solutions\",\"publisher\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hinges-htan.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/#organization\",\"name\":\"HTAN Industrial Hinges Manufacturer\",\"url\":\"https:\/\/hinges-htan.com\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"contentUrl\":\"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png\",\"width\":726,\"height\":172,\"caption\":\"HTAN Industrial Hinges Manufacturer\"},\"image\":{\"@id\":\"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dobradi\u00e7a de pl\u00e1stico ajust\u00e1vel de torque - Leve, silenciosa e dur\u00e1vel - Dobradi\u00e7as Fabricante","description":"A dobradi\u00e7a de bin\u00e1rio de pl\u00e1stico ajust\u00e1vel (PA6, 270\u00b0) proporciona um movimento suave e silencioso e durabilidade - perfeita para dispositivos dom\u00e9sticos e m\u00e9dicos inteligentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/","og_locale":"pt_PT","og_type":"article","og_title":"Adjustable Plastic Torque Hinge \u2014 Lightweight, Quiet &amp; Durable - Hinges Manufacturer","og_description":"Adjustable plastic torque hinge (PA6, 270\u00b0) delivers smooth, quiet motion and durability\u2014perfect for smart home and medical devices.","og_url":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/","og_site_name":"Hinges Manufacturer","article_modified_time":"2025-12-17T05:44:56+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-7.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/","url":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/","name":"Dobradi\u00e7a de pl\u00e1stico ajust\u00e1vel de torque - Leve, silenciosa e dur\u00e1vel - Dobradi\u00e7as Fabricante","isPartOf":{"@id":"https:\/\/hinges-htan.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/#primaryimage"},"image":{"@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/#primaryimage"},"thumbnailUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-7.webp","datePublished":"2025-10-22T06:50:15+00:00","dateModified":"2025-12-17T05:44:56+00:00","description":"A dobradi\u00e7a de bin\u00e1rio de pl\u00e1stico ajust\u00e1vel (PA6, 270\u00b0) proporciona um movimento suave e silencioso e durabilidade - perfeita para dispositivos dom\u00e9sticos e m\u00e9dicos inteligentes.","breadcrumb":{"@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hinges-htan.com\/product\/adjustable-plastic-torque-hinge\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/#primaryimage","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-7.webp","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/10\/Adjustable-plastic-torque-hinge-7.webp","width":500,"height":500,"caption":"Adjustable plastic torque hinge"},{"@type":"BreadcrumbList","@id":"https:\/\/hinges-htan.com\/pt\/produto\/dobradica-de-binario-de-plastico-ajustavel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/hinges-htan.com\/pt\/"},{"@type":"ListItem","position":2,"name":"\u4ea7\u54c1","item":"https:\/\/hinges-htan.com\/pt\/produtos\/"},{"@type":"ListItem","position":3,"name":"Adjustable Plastic Torque Hinge \u2014 Lightweight, Quiet &amp; Durable"}]},{"@type":"WebSite","@id":"https:\/\/hinges-htan.com\/pt\/#website","url":"https:\/\/hinges-htan.com\/pt\/","name":"HTAN Dobradi\u00e7as Industriais Fabricante","description":"Solu\u00e7\u00f5es de dobradi\u00e7as para arm\u00e1rios e gabinetes","publisher":{"@id":"https:\/\/hinges-htan.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hinges-htan.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/hinges-htan.com\/pt\/#organization","name":"HTAN Dobradi\u00e7as Industriais Fabricante","url":"https:\/\/hinges-htan.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","contentUrl":"https:\/\/hinges-htan.com\/wp-content\/uploads\/2025\/06\/htan-logo.png","width":726,"height":172,"caption":"HTAN Industrial Hinges Manufacturer"},"image":{"@id":"https:\/\/hinges-htan.com\/pt\/#\/schema\/logo\/image\/"}}]}},"acf":{"_product_image_gallery":[3853,3854,3855,3856,3857,3858],"_product_excerpt":"Manufacturer: HTAN\r\nModel: XG11-061 \/ XG11-062\r\nUnit Price: Get Latest Price\r\nMOQ: 1 Piece\r\nLead Time: In Stock (Ships within 24h) \/20-25 Days for Custom\r\nCustomization: OEM \/ ODM Support","post_download_file":3860},"_links":{"self":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/wpkj_product\/3851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/wpkj_product"}],"about":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/types\/wpkj_product"}],"author":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/wpkj_product\/3851\/revisions"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3858"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3857"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3856"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3855"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3854"},{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media\/3859"}],"wp:attachment":[{"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/media?parent=3851"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/product_cat?post=3851"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hinges-htan.com\/pt\/wp-json\/wp\/v2\/product_tag?post=3851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}